{"id":71,"count":1,"description":"","link":"https:\/\/www.blognoel.com\/de\/weihnachten\/twitter\/","name":"Twitter","slug":"twitter","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.blognoel.com\/de\/wp-json\/wp\/v2\/tags\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blognoel.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.blognoel.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.blognoel.com\/de\/wp-json\/wp\/v2\/posts?tags=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}